{"id":301,"date":"2018-07-27T15:49:39","date_gmt":"2018-07-27T18:49:39","guid":{"rendered":"https:\/\/www.amarilfranklin.com.br\/?page_id=301"},"modified":"2021-02-04T11:05:32","modified_gmt":"2021-02-04T14:05:32","slug":"legislacao-e-regras","status":"publish","type":"page","link":"https:\/\/www.amarilfranklin.com.br\/index.php\/legislacao-e-regras\/","title":{"rendered":"Legisla\u00e7\u00e3o e Regras"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;3.22&#8243; custom_padding=&#8221;||0px|||&#8221;][et_pb_row column_structure=&#8221;1_4,3_4&#8243; admin_label=&#8221;row&#8221; module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;94%&#8221; width_tablet=&#8221;80%&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;94%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; make_fullwidth=&#8221;on&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;on&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/www.amarilfranklin.com.br\/wp-content\/uploads\/2018\/08\/balan\u00e7a.png?_t=1586799383&#8243; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Imagem&#8221; _builder_version=&#8221;4.4.3&#8243; sticky=&#8221;off&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; always_center_on_mobile=&#8221;on&#8221;]&nbsp;<br \/>\n[\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Texto&#8221; _builder_version=&#8221;4.5.6&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postmetadataheader\">\n<h1 class=\"tresbf-postheader\" style=\"text-align: center;\">Legisla\u00e7\u00e3o e Regras<\/h1>\n<\/div>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<p>Conhe\u00e7a as principais legisla\u00e7\u00f5es e regras que regulamentam os par\u00e2metros de atua\u00e7\u00e3o do mercado financeiro. As normas, regras e instru\u00e7\u00f5es s\u00e3o abrangentes e re\u00fanem desde conduta da corretora em rela\u00e7\u00e3o \u00e0s bolsas de valores at\u00e9 determina\u00e7\u00f5es sobre opera\u00e7\u00f5es sujeitas a procedimentos especiais.<\/p>\n<p>Veja tamb\u00e9m os sites dos Reguladores de Mercado: |<a href=\"https:\/\/www.bcb.gov.br\">Banco Central<\/a>| <a href=\"http:\/\/www.cvm.gov.br\/\">CVM<\/a> |<a href=\"https:\/\/www.bsmsupervisao.com.br\/\">BSM<\/a>|<a href=\"http:\/\/www.b3.com.br\/pt_br\/\">B3<\/a>|<\/p>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; admin_label=&#8221;row&#8221; module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;94%&#8221; width_tablet=&#8221;80%&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;94%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; make_fullwidth=&#8221;on&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;on&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Texto&#8221; _builder_version=&#8221;4.5.6&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Instru\u00e7\u00f5es CVM<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Instru\u00e7\u00e3o CVM 51&#8243; _builder_version=&#8221;4.5.6&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"http:\/\/www.cvm.gov.br\/legislacao\/instrucoes\/inst051.html\" target=\"_blank\" rel=\"noopener noreferrer\">Instru\u00e7\u00e3o CVM 51<\/a><\/h3>\n<p style=\"text-align: justify;\">Aprovada em 9 de junho de 1986, a Instru\u00e7\u00e3o 51, elaborada pela CVM, regulamenta a concess\u00e3o, pelas Sociedades Corretoras, de financiamento para compra de a\u00e7\u00f5es e o empr\u00e9stimo de a\u00e7\u00f5es para venda, dentro de determinados crit\u00e9rios, os chamados empr\u00e9stimos em Conta Margem. Em ambos os casos, s\u00e3o definidos os padr\u00f5es do contrato de financiamento. Assim como em qualquer concess\u00e3o de empr\u00e9stimo tamb\u00e9m dever\u00e3o oferecer garantias. Para fins de registro do financiamento concedido a corretora abrir\u00e1 uma conta corrente especial em nome de cada financiado. Em rela\u00e7\u00e3o ao volume total das opera\u00e7\u00f5es concedidas pela sociedade corretora ou distribuidora n\u00e3o poder\u00e1 exceder a cinco vezes o valor do respectivo patrim\u00f4nio l\u00edquido.<\/p>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: justify;\"><a href=\"http:\/\/www.cvm.gov.br\/legislacao\/instrucoes\/inst051.html\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Instru\u00e7\u00e3o CVM 168&#8243; _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"http:\/\/www.cvm.gov.br\/legislacao\/instrucoes\/inst168.html\" target=\"_blank\" rel=\"noopener noreferrer\">Instru\u00e7\u00e3o CVM 168<\/a><\/h3>\n<p style=\"text-align: justify;\">A Instru\u00e7\u00e3o da CVM, em vigor desde 23 de dezembro 1991, disp\u00f5e sobre as opera\u00e7\u00f5es sujeitas a procedimentos especiais nas bolsas de valores. \u00c9 o caso de elevada quantidade de a\u00e7\u00f5es ou direitos superior \u00e0 m\u00e9dia di\u00e1ria negociada nos \u00faltimos preg\u00f5es, qualquer bloco substancial, mesmo que a negocia\u00e7\u00e3o n\u00e3o envolva transfer\u00eancia de controle ou de pre\u00e7o sensivelmente superior ou inferior \u00e0 m\u00e9dia dos \u00faltimos preg\u00f5es. \u00c9 muito importante a leitura desta Instru\u00e7\u00e3o, pois \u00e9 atrav\u00e9s dela que algumas opera\u00e7\u00f5es j\u00e1 confirmadas, podem ser canceladas pela Bolsa, no caso de ocorr\u00eancia de alguma irregularidade ou n\u00e3o obedi\u00eancia aos par\u00e2metros e procedimentos aqui descritos.<\/p>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: justify;\"><a href=\"http:\/\/www.cvm.gov.br\/legislacao\/instrucoes\/inst168.html\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Instru\u00e7\u00e3o CVM 400&#8243; _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"http:\/\/www.cvm.gov.br\/legislacao\/instrucoes\/inst400.html\" target=\"_blank\" rel=\"noopener noreferrer\">Instru\u00e7\u00e3o CVM 400<\/a><\/h3>\n<p style=\"text-align: justify;\">Em vigor desde 29 de dezembro de 2003, elaborada pela CVM, a legisla\u00e7\u00e3o regulamenta ofertas p\u00fablicas de distribui\u00e7\u00e3o, nos mercados prim\u00e1rio e secund\u00e1rio, de a\u00e7\u00f5es em bolsa de valores, bolsa de mercadorias e de futuros e entidade do mercado de balc\u00e3o organizado. Segundo a Instru\u00e7\u00e3o, toda oferta p\u00fablica para distribui\u00e7\u00e3o de a\u00e7\u00f5es no mercado dever\u00e1 obter registro junto a CVM. O pedido de registro ser\u00e1 analisado no per\u00edodo de 20 dias. Ela disp\u00f5e sobre todos os procedimentos que envolvem a oferta p\u00fablica de a\u00e7\u00f5es no mercado desde o registro at\u00e9 informa\u00e7\u00f5es que dever\u00e3o constar no material de divulga\u00e7\u00e3o ao p\u00fablico.<\/p>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: justify;\"><a href=\"http:\/\/www.cvm.gov.br\/legislacao\/instrucoes\/inst400.html\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Instru\u00e7\u00e3o CVM 441&#8243; _builder_version=&#8221;4.6.6&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"http:\/\/www.cvm.gov.br\/legislacao\/instrucoes\/inst441.html\" target=\"_blank\" rel=\"noopener noreferrer\">Instru\u00e7\u00e3o CVM 441<\/a><\/h3>\n<p style=\"text-align: justify;\">Regulamentada pela CVM em 10 de novembro de 2006, a Instru\u00e7\u00e3o disp\u00f5e sobre Disp\u00f5e sobre empr\u00e9stimo de valores mobili\u00e1rios por entidades de compensa\u00e7\u00e3o e liquida\u00e7\u00e3o de opera\u00e7\u00f5es\u00a0com valores mobili\u00e1rios. Pela norma, o servi\u00e7o de empr\u00e9stimo pelas institui\u00e7\u00f5es dever\u00e1 ter aprova\u00e7\u00e3o pr\u00e9via da CVM. Tamb\u00e9m regulamenta que as sociedades corretoras e distribuidoras de valores s\u00e3o as institui\u00e7\u00f5es que far\u00e3o a intermedia\u00e7\u00e3o das opera\u00e7\u00f5es. Determina quais as informa\u00e7\u00f5es dever\u00e3o ser mencionadas no contrato de empr\u00e9stimo.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.cvm.gov.br\/legislacao\/instrucoes\/inst441.html\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/p>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Instru\u00e7\u00e3o 505 CVM&#8221; _builder_version=&#8221;4.6.6&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postmetadataheader\"><\/div>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"http:\/\/www.cvm.gov.br\/legislacao\/instrucoes\/inst505.html\" target=\"_blank\" rel=\"noopener noreferrer\">Instru\u00e7\u00e3o CVM 505<\/a><\/h3>\n<p style=\"text-align: justify;\">Legisla\u00e7\u00e3o da CVM, de 27 de setembro de 2011, com altera\u00e7\u00f5es feitas em 2019, trata das normas e procedimentos a serem observados nas opera\u00e7\u00f5es realizadas com valores mobili\u00e1rios em mercados regulamentados de valores mobili\u00e1rios. Ela determina que as corretoras elaborem suas regras e par\u00e2metros de atua\u00e7\u00e3o na rela\u00e7\u00e3o com seus clientes. Este documento deve conter defini\u00e7\u00f5es sobre as normas relativas \u00e0 recep\u00e7\u00e3o de ordens, ao tipo de ordens aceitas, \u00e0s confirma\u00e7\u00f5es e cancelamento de neg\u00f3cios, entre outras. \u00c9 vedado \u00e0s corretoras aceitar ou cumprir ordens de clientes que n\u00e3o estejam previamente cadastrados, entre outros diversos itens.<\/p>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: justify;\"><a href=\"http:\/\/www.cvm.gov.br\/legislacao\/instrucoes\/inst505.html\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Instru\u00e7\u00e3o CVM 617&#8243; _builder_version=&#8221;4.6.6&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"http:\/\/www.cvm.gov.br\/legislacao\/instrucoes\/inst617.html\" target=\"_blank\" rel=\"noopener noreferrer\">Instru\u00e7\u00e3o CVM 617<\/a><\/h3>\n<p style=\"text-align: justify;\">Em vigor desde 05 de dezembro de 2019, a Instru\u00e7\u00e3o Normativa da CVM disp\u00f5e sobre a preven\u00e7\u00e3o \u00e0 lavagem de dinheiro e ao financiamento do terrorismo \u2013 PLDFT no \u00e2mbito do mercado de valores mobili\u00e1rios. A Instru\u00e7\u00e3o define, por exemplo, as informa\u00e7\u00f5es que devem ser indispens\u00e1veis para os cadastros de pessoa f\u00edsica e jur\u00eddica. Segundo a Instru\u00e7\u00e3o, as corretoras dever\u00e3o conservar os cadastros pelo per\u00edodo m\u00ednimo de cinco anos, ficando \u00e0 disposi\u00e7\u00e3o da CVM, entre outros itens. Ela lista as situa\u00e7\u00f5es pr\u00e1ticas que configuram os crimes definidos na Lei 9.613 e que devem ser comunicados \u00e0 CVM pelas corretoras e bolsas quando tiverem ind\u00edcios ou configurarem crimes caracterizados pelo documento.<\/p>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: justify;\"><a href=\"http:\/\/www.cvm.gov.br\/legislacao\/instrucoes\/inst617.html\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Texto&#8221; _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Resolu\u00e7\u00f5es e Leis<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Resolu\u00e7\u00e3o 2.690 BCDB&#8221; _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"https:\/\/www.bcb.gov.br\/pre\/normativos\/busca\/downloadNormativo.asp?arquivo=\/Lists\/Normativos\/Attachments\/47428\/Res_2690_v4_P.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Resolu\u00e7\u00e3o 2.690 Banco Central do Brasil<\/a><\/h3>\n<p style=\"text-align: justify;\">A legisla\u00e7\u00e3o disciplina a constitui\u00e7\u00e3o , organiza\u00e7\u00e3o e o funcionamento das Bolsas de Valores. A Resolu\u00e7\u00e3o em vigor desde em 26 de outubro de 1989, torna as Bolsas de Valores associa\u00e7\u00f5es civis, sem fins lucrativos, tendo como objetivo manter o local adequado \u00e0s opera\u00e7\u00f5es de compra e venda de t\u00edtulos e valores mobili\u00e1rios, em mercado livre e aberto, organizado e fiscalizado pela pr\u00f3pria Bolsa. Al\u00e9m de dotar, permanentemente, o local ou sistema de todos os meios necess\u00e1rios \u00e0 pronta e eficiente realiza\u00e7\u00e3o e visibilidade das opera\u00e7\u00f5es, entre outras responsabilidades.<\/p>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: justify;\"><a href=\"https:\/\/www.bcb.gov.br\/pre\/normativos\/busca\/downloadNormativo.asp?arquivo=\/Lists\/Normativos\/Attachments\/47428\/Res_2690_v4_P.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Resolu\u00e7\u00e3o 2817 BCDB&#8221; _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"https:\/\/www.bcb.gov.br\/pre\/normativos\/res\/2001\/pdf\/res_2817_v2_P.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Resolu\u00e7\u00e3o 2.817 Banco Central do Brasil<\/a><\/h3>\n<p style=\"text-align: justify;\">Aprovada em 22 de fevereiro de 2001 pelo Banco Central do Brasil, a legisla\u00e7\u00e3o permite \u00e0s institui\u00e7\u00f5es banc\u00e1rias ou financeiras a abertura de conta e movimenta\u00e7\u00e3o de contas exclusivamente pelo meio eletr\u00f4nico.<\/p>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: justify;\"><a href=\"https:\/\/www.bcb.gov.br\/pre\/normativos\/res\/2001\/pdf\/res_2817_v2_P.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Resolu\u00e7\u00e3o 296 CA BSM&#8221; _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"https:\/\/www.bsmsupervisao.com.br\/assets\/file\/leis-normas-regras\/BOVESPA-Resolu%C3%A7%C3%A3o-CA-296-2006.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Resolu\u00e7\u00e3o 296 CA BSM<\/a><\/h3>\n<p style=\"text-align: justify;\">Resolu\u00e7\u00e3o do Conselho de Administra\u00e7\u00e3o da BOVESPA, de 22 de julho de 2003, regulamenta e disp\u00f5e sobre a uniformiza\u00e7\u00e3o dos cadastros dos clientes das sociedades corretoras, em atendimento \u00e0s exig\u00eancias da Instru\u00e7\u00e3o CVM 387. Segundo esta resolu\u00e7\u00e3o, as corretoras dever\u00e3o manter cadastros atualizados de seus clientes, dentro de um padr\u00e3o m\u00ednimo de informa\u00e7\u00f5es.<\/p>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: justify;\"><a href=\"https:\/\/www.bsmsupervisao.com.br\/assets\/file\/leis-normas-regras\/BOVESPA-Resolu%C3%A7%C3%A3o-CA-296-2006.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Lei 6.385&#8243; _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/L6385.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Lei 6.385<\/a><\/h3>\n<p style=\"text-align: justify;\">Criada em 31 de dezembro de 1964, a Lei disp\u00f5e sobre a cria\u00e7\u00e3o da Comiss\u00e3o de Valores Mobili\u00e1rios (CVM), o principal \u00f3rg\u00e3o regulador do mercado de capitais. A CVM \u00e9 uma entidade aut\u00e1rquica em regime especial, vinculada ao Minist\u00e9rio da Fazenda, com personalidade jur\u00eddica e patrim\u00f4nio pr\u00f3prios, dotada de autoridade administrativa independente, aus\u00eancia de subordina\u00e7\u00e3o hier\u00e1rquica, mandato fixo e estabilidade de seus dirigentes, autonomia financeira e or\u00e7ament\u00e1ria.<\/p>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: justify;\"><a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/L6385.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Lei 6.404&#8243; _builder_version=&#8221;4.6.6&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<h3><a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/LEIS\/L6404consol.htm\">Lei 6.404<\/a><\/h3>\n<p style=\"text-align: justify;\">Criada em 15 de Dezembro de 1976, e com algumas altera\u00e7\u00f5es posteriores, \u00e9 a Lei que disp\u00f5e sobre as Sociedades por A\u00e7\u00f5es no Brasil. As Sociedades An\u00f4nimas, tamb\u00e9m chamadas de companhia ou sociedades por a\u00e7\u00f5es, \u00e9 nome dado a uma empresa com fins lucrativos que tem seu capital dividido em a\u00e7\u00f5es e a responsabilidade de seus s\u00f3cios (acionistas) limitada ao pre\u00e7o e ao tipo da emiss\u00e3o das a\u00e7\u00f5es subscritas ou adquiridas. A Lei 6.404\/76 regulamenta todo o funcionamento de uma sociedade an\u00f4nima, desde a sua constitui\u00e7\u00e3o at\u00e9 a distribui\u00e7\u00e3o de lucros.<\/p>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: justify;\"><a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/LEIS\/L6404consol.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Lei 9.613&#8243; _builder_version=&#8221;4.6.6&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/Leis\/L9613.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Lei 9.613<\/a><\/h3>\n<p style=\"text-align: justify;\">Aprovada em 3 de mar\u00e7o de 1998, a Lei 9.613 trata dos crimes de &#8220;lavagem&#8221; de dinheiro, da utiliza\u00e7\u00e3o do sistema financeiro para a\u00e7\u00f5es il\u00edcitas e cria o Conselho de Controle de Atividades Financeiras (COAF). O COAF tem como objetivo disciplinar, aplicar penas administrativas, receber, examinar e identificar as ocorr\u00eancias suspeitas de atividades il\u00edcitas previstas nesta Lei, sem preju\u00edzo da compet\u00eancia de outros \u00f3rg\u00e3os e entidades. A Lei caracteriza como crime pass\u00edvel de pena de reclus\u00e3o, ocultar ou dissimular a natureza, origem e localiza\u00e7\u00e3o, movimenta\u00e7\u00e3o ou propriedade de bens, direitos ou valores provenientes de crimes de tr\u00e1fico il\u00edcito de subst\u00e2ncias entorpecentes ou drogas afins; terrorismo; contrabando ou tr\u00e1fico de armas, muni\u00e7\u00f5es ou material destinado \u00e0 sua produ\u00e7\u00e3o; extors\u00e3o mediante seq\u00fcestro; a\u00e7\u00f5es contra a Administra\u00e7\u00e3o P\u00fablica; contra o sistema financeiro nacional e os praticados por organiza\u00e7\u00e3o criminosa. A penalidade prevista varia de tr\u00eas a dez anos de reclus\u00e3o, mais multa. A Lei determina que as entidades respons\u00e1veis pela intermedia\u00e7\u00e3o, negocia\u00e7\u00e3o devam manter cadastro atualizado de seus clientes, al\u00e9m do registro de todas as opera\u00e7\u00f5es realizadas por seus clientes, que devem estar \u00e0 disposi\u00e7\u00e3o para atender qualquer pedido de autoridade competente.<\/p>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: justify;\"><a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/Leis\/L9613.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Lei 13.709&#8243; _builder_version=&#8221;4.6.6&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/_ato2015-2018\/2018\/lei\/l13709.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Lei 13.709<\/a><\/h3>\n<p style=\"text-align: justify;\">Aprovada em 14 de agosto de 2018, a Lei 13.709 trata disp\u00f5e sobre o tratamento de dados pessoais, inclusive nos meios digitais, por pessoa natural ou por pessoa jur\u00eddica de direito p\u00fablico ou privado, com o objetivo de proteger os direitos fundamentais de liberdade e de privacidade e o livre desenvolvimento da personalidade da pessoa natural. Est\u00e1 lei \u00e9 conhecida como Lei Geral de Prote\u00e7\u00e3o de Dados Pessoais (LGPD).<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<h6 style=\"text-align: justify;\"><a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/_ato2015-2018\/2018\/lei\/l13709.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Texto&#8221; _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Regulamentos e Regras<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Regulamento de Opera\u00e7\u00f5es Bolsa de Valores de S\u00e3o Paulo&#8221; _builder_version=&#8221;4.4.7&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"https:\/\/www.bsmsupervisao.com.br\/assets\/file\/leis-normas-regras\/bovespa-regulamento-de-operacoes-2007-07-25.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Regulamento de Opera\u00e7\u00f5es Bolsa de Valores de S\u00e3o Paulo<\/a><\/h3>\n<p style=\"text-align: justify;\">Re\u00fane a consolida\u00e7\u00e3o das regras do sistema de negocia\u00e7\u00e3o na Bovespa, com cap\u00edtulos dedicados aos tipos de negocia\u00e7\u00e3o, ao preg\u00e3o eletr\u00f4nico, local de negocia\u00e7\u00e3o, aos operadores e auxiliares do preg\u00e3o, after market, mercado \u00e0 vista, a termo, futuro e de op\u00e7\u00f5es, formadores de mercado, ordens de compra e venda, as apregoa\u00e7\u00f5es, procedimentos especiais de leil\u00e3o, corre\u00e7\u00e3o e cancelamento de neg\u00f3cios, direitos e obriga\u00e7\u00f5es das sociedades corretoras, entre outros.<\/p>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: justify;\"><a href=\"https:\/\/www.bsmsupervisao.com.br\/assets\/file\/leis-normas-regras\/bovespa-regulamento-de-operacoes-2007-07-25.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Regulamento de Opera\u00e7\u00f5es da CBLC&#8221; _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"http:\/\/www.b3.com.br\/data\/files\/2C\/06\/4C\/89\/A2D6F6109A4874F6AC094EA8\/Regulamento%20da%20Camara%20de%20Compensacao%20e%20Liquidacao%20da%20BMFBOVESPA_20191230.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Regulamento de Opera\u00e7\u00f5es da CBLC<\/a><\/h3>\n<p style=\"text-align: justify;\">O regulamento tem como objetivo disciplinar as atividades da Companhia Brasileira de Liquida\u00e7\u00e3o e Cust\u00f3dia (CBLC). Al\u00e9m disso, regulamenta os princ\u00edpios e regras gerais para institui\u00e7\u00f5es ou pessoas com as quais mant\u00e9m qualquer tipo de rela\u00e7\u00e3o jur\u00eddica contratual ou operacional.<\/p>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: justify;\"><a href=\"http:\/\/www.b3.com.br\/data\/files\/2C\/06\/4C\/89\/A2D6F6109A4874F6AC094EA8\/Regulamento%20da%20Camara%20de%20Compensacao%20e%20Liquidacao%20da%20BMFBOVESPA_20191230.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Regulamento do Tesouro Direto&#8221; _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"https:\/\/www.tesourodireto.com.br\/conheca\/regras.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Regulamento do Tesouro Direto<\/a><\/h3>\n<p style=\"text-align: justify;\">Este documento re\u00fane as regras que disciplinam as atividades da Secretaria do Tesouro Nacional (STN), Companhia Brasileira de Liquida\u00e7\u00e3o e Cust\u00f3dia (CBLC), dos agentes de cust\u00f3dia da CBLC e dos Investidores nas opera\u00e7\u00f5es envolvendo t\u00edtulos p\u00fablicos federais no sistema denominado \u201cTesouro Direto\u201d. Os Agentes de Cust\u00f3dia, no caso as corretoras, s\u00e3o respons\u00e1veis pela autenticidade das informa\u00e7\u00f5es cadastrais do Investidor, devendo manter em seus arquivos documenta\u00e7\u00e3o e ficha cadastrais sempre atualizadas, sob pena da aplica\u00e7\u00e3o das penalidades previstas neste Regulamento e nas demais normas da CBLC. Eles devem enviar sempre que for solicitada, documenta\u00e7\u00e3o comprobat\u00f3ria das informa\u00e7\u00f5es cadastrais dos Investidores. O acesso do investidor ser\u00e1 realizado pela internet, diretamente pelo site oficial do Tesouro Direto, mediante preenchimento de seu CPF e senha. A habilita\u00e7\u00e3o do investidor dever\u00e1 ser por interm\u00e9dio de um agente de cust\u00f3dia para acessar o Tesouro Direto e receber\u00e1 da CBLC, em seu endere\u00e7o eletr\u00f4nico, uma senha provis\u00f3ria para acesso ao Tesouro Direto. Esta senha possui um prazo de validade predefinido e dever\u00e1 ser alterada, pelo Investidor, em seu primeiro acesso ao Tesouro Direto.<\/p>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: justify;\"><a href=\"https:\/\/www.tesourodireto.com.br\/conheca\/regras.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Manual de procedimentos operacionais da c\u00e2mara de compensa\u00e7\u00e3o e liquida\u00e7\u00e3o&#8221; _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"http:\/\/www.b3.com.br\/data\/files\/30\/52\/6D\/51\/E72607104F6DA507AC094EA8\/Manual%20de%20Procedimentos%20Operacionais%20da%20Camara%20BMFBOVESPA.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Manual de procedimentos operacionais da c\u00e2mara de compensa\u00e7\u00e3o e liquida\u00e7\u00e3o<\/a><\/h3>\n<p style=\"text-align: justify;\">Est\u00e3o descritos neste manual de procedimentos operacionais os processos e os procedimentos relacionados com as atividades realizadas pela c\u00e2mara e por seus participantes, em rela\u00e7\u00e3o aos mercados de derivativos financeiros, de commodities e de renda vari\u00e1vel, ao mercado de empr\u00e9stimo de ativos e aos mercados a vista de ouro, de renda vari\u00e1vel e de renda fixa privada administrados pela BM&amp;FBOVESPA, abrangendo as opera\u00e7\u00f5es realizadas em mercado de bolsa e em mercado de balc\u00e3o organizado.<\/p>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: justify;\"><a href=\"http:\/\/www.b3.com.br\/data\/files\/30\/52\/6D\/51\/E72607104F6DA507AC094EA8\/Manual%20de%20Procedimentos%20Operacionais%20da%20Camara%20BMFBOVESPA.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;C\u00f3digo de Conduta B3&#8243; _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"https:\/\/www.bsmsupervisao.com.br\/assets\/file\/codigo-conduta\/CodigoDeConduta.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">C\u00f3digo de Conduta B3<\/a><\/h3>\n<p style=\"text-align: justify;\">Estabelece os princ\u00edpios gerais e as regras que regem a conduta dos participantes nos mercados administrados pela B3; utiliza\u00e7\u00e3o dos Sistemas de Negocia\u00e7\u00e3o e\/ou dos Sistemas de Registro desenvolvidos ou administrados pela B3; utiliza\u00e7\u00e3o de qualquer servi\u00e7o prestado pela B3 nos termos de seus Estatutos Sociais. O C\u00f3digo prev\u00ea que os atos e as negocia\u00e7\u00f5es realizados na B3 dever\u00e3o estar de acordo com as regras e as finalidades das modalidades operacionais adotadas, em sintonia com os mecanismos de negocia\u00e7\u00e3o e o processo de forma\u00e7\u00e3o de pre\u00e7os. \u00c9 vedada a atua\u00e7\u00e3o dos participantes, isolada ou em conjunto, com objetivo de afetar os mecanismos de forma\u00e7\u00e3o de pre\u00e7os, criando condi\u00e7\u00f5es artificiais de oferta ou demanda, ou seja, de manipula\u00e7\u00e3o do mercado.<\/p>\n<p>&nbsp;<\/p>\n<h6 style=\"text-align: justify;\"><a href=\"https:\/\/www.bsmsupervisao.com.br\/assets\/file\/codigo-conduta\/CodigoDeConduta.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;LEGISLA\u00c7\u00c3O E REGULAMENTA\u00c7\u00c3O | LEIS, NORMAS E REGRAS&#8221; _builder_version=&#8221;4.5.6&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\">\n<div class=\"tresbf-article\">\n<h3><a href=\"https:\/\/www.bsmsupervisao.com.br\/legislacao-e-regulamentacao\/leis-normas-e-regras\">LEGISLA\u00c7\u00c3O E REGULAMENTA\u00c7\u00c3O | LEIS, NORMAS E REGRAS<\/a><\/h3>\n<p>P\u00e1gina da BSM Supervis\u00e3o de Mercados, empresa da B3\u00a0 que contempla as principais Leis, Normas e Regras\u00a0<span>que se aplicam aos Participantes dos mercados de valores mobili\u00e1rios.\u00a0<\/span><\/p>\n<p><span><\/span><\/p>\n<p><span><\/span><\/p>\n<h6 style=\"text-align: justify;\"><a href=\"https:\/\/www.bsmsupervisao.com.br\/legislacao-e-regulamentacao\/leis-normas-e-regras\" target=\"_blank\" rel=\"noopener noreferrer\">Confira a \u00edntegra&gt;&gt;<\/a><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Se\u00e7\u00e3o&#8221; _builder_version=&#8221;3.22&#8243; custom_margin=&#8221;-56px|||||&#8221; custom_padding=&#8221;0px|||||&#8221; transparent_background=&#8221;off&#8221; make_fullwidth=&#8221;off&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;on&#8221; global_module=&#8221;6602&#8243;][et_pb_row use_custom_gutter=&#8221;on&#8221; admin_label=&#8221;Linha&#8221; _builder_version=&#8221;3.25&#8243; width=&#8221;90%&#8221; max_width=&#8221;1600px&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Texto&#8221; _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;||69px|||&#8221; custom_padding=&#8221;27px|||||&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<h4 style=\"text-align: center;\">Conhe\u00e7a os nossos produtos!<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; disabled_on=&#8221;on|on|&#8221; admin_label=&#8221;Linha&#8221; _builder_version=&#8221;3.25&#8243; width=&#8221;90%&#8221; max_width=&#8221;1600px&#8221; make_fullwidth=&#8221;off&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;on&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_button button_url=&#8221;https:\/\/www.amarilfranklin.com.br\/index.php\/cambio\/&#8221; button_text=&#8221;C\u00e2mbio&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;C\u00e2mbio&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14&#8243; button_letter_spacing_hover=&#8221;0&#8243; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;0&#8243; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>\u00a0<\/p>\n<p>[\/et_pb_button][et_pb_button button_url=&#8221;https:\/\/www.amarilfranklin.com.br\/index.php\/fundos-de-investimento-amaril-franklin\/&#8221; button_text=&#8221;Fundos de Investimentos&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;Fundos de Investimentos&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14&#8243; button_letter_spacing_hover=&#8221;0&#8243; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;0&#8243; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>\u00a0<\/p>\n<p>[\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_button button_url=&#8221;https:\/\/www.amarilfranklin.com.br\/index.php\/renda-fixa\/&#8221; button_text=&#8221;Renda Fixa&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;Renda Fixa&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14&#8243; button_letter_spacing_hover=&#8221;0&#8243; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;0&#8243; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>\u00a0<\/p>\n<p>[\/et_pb_button][et_pb_button button_url=&#8221;https:\/\/www.amarilfranklin.com.br\/index.php\/clube-de-investimento\/&#8221; button_text=&#8221;Clubes de Investimentos&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;Clubes de Investimentos&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14&#8243; button_letter_spacing_hover=&#8221;0&#8243; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;0&#8243; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>\u00a0<\/p>\n<p>[\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_button button_url=&#8221;https:\/\/www.amarilfranklin.com.br\/index.php\/mercado-de-acoes\/&#8221; button_text=&#8221;Mercado de A\u00e7\u00f5es&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;Mercado de A\u00e7\u00f5es&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14&#8243; button_letter_spacing_hover=&#8221;0&#8243; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;0&#8243; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>\u00a0<\/p>\n<p>[\/et_pb_button][et_pb_button button_url=&#8221;https:\/\/www.amarilfranklin.com.br\/index.php\/opa-fechamento-de-capital\/&#8221; button_text=&#8221;Fechamento de Capital &#8211; OPA&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;Fechamento de Capital &#8211; OPA&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14&#8243; button_letter_spacing_hover=&#8221;0&#8243; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;0&#8243; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>\u00a0<\/p>\n<p>[\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; disabled_on=&#8221;||on&#8221; admin_label=&#8221;Linha&#8221; _builder_version=&#8221;3.25&#8243; width=&#8221;90%&#8221; max_width=&#8221;1600px&#8221; make_fullwidth=&#8221;off&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;on&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_button button_url=&#8221;https:\/\/www.amarilfranklin.com.br\/index.php\/cambio\/&#8221; button_text=&#8221;C\u00e2mbio&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;C\u00e2mbio&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14&#8243; button_letter_spacing_hover=&#8221;0&#8243; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;0&#8243; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>\u00a0<\/p>\n<p>[\/et_pb_button][et_pb_button button_url=&#8221;https:\/\/www.amarilfranklin.com.br\/index.php\/renda-fixa\/&#8221; button_text=&#8221;Renda Fixa&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;Renda Fixa&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14&#8243; button_letter_spacing_hover=&#8221;0&#8243; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;0&#8243; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>\u00a0<\/p>\n<p>[\/et_pb_button][et_pb_button button_url=&#8221;https:\/\/www.amarilfranklin.com.br\/index.php\/mercado-de-acoes\/&#8221; button_text=&#8221;Mercado de A\u00e7\u00f5es&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;Mercado de A\u00e7\u00f5es&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14&#8243; button_letter_spacing_hover=&#8221;0&#8243; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;0&#8243; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>\u00a0<\/p>\n<p>[\/et_pb_button][et_pb_button button_url=&#8221;https:\/\/www.amarilfranklin.com.br\/index.php\/clube-de-investimento\/&#8221; button_text=&#8221;Clubes de Investimentos&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;Clubes de Investimento&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14&#8243; button_letter_spacing_hover=&#8221;0&#8243; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;0&#8243; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>\u00a0<\/p>\n<p>[\/et_pb_button][et_pb_button button_url=&#8221;https:\/\/www.amarilfranklin.com.br\/index.php\/fundos-de-investimento-amaril-franklin\/&#8221; button_text=&#8221;Fundos de Investimentos&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;Fundos de Investimentos&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14&#8243; button_letter_spacing_hover=&#8221;0&#8243; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;0&#8243; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>\u00a0<\/p>\n<p>[\/et_pb_button][et_pb_button button_url=&#8221;https:\/\/www.amarilfranklin.com.br\/index.php\/opa-fechamento-de-capital\/&#8221; button_text=&#8221;Fechamento de Capital &#8211; OPA&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;Fechamento de Capital &#8211; OPA&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14&#8243; button_letter_spacing_hover=&#8221;0&#8243; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;0&#8243; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>\u00a0<\/p>\n<p>[\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Legisla\u00e7\u00e3o e Regras Conhe\u00e7a as principais legisla\u00e7\u00f5es e regras que regulamentam os par\u00e2metros de atua\u00e7\u00e3o do mercado financeiro. As normas, regras e instru\u00e7\u00f5es s\u00e3o abrangentes e re\u00fanem desde conduta da corretora em rela\u00e7\u00e3o \u00e0s bolsas de valores at\u00e9 determina\u00e7\u00f5es sobre opera\u00e7\u00f5es sujeitas a procedimentos especiais. Veja tamb\u00e9m os sites dos Reguladores de Mercado: |Banco [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<div class=\"tresbf-postmetadataheader\"><h2 class=\"tresbf-postheader\">\u00a0<\/h2><\/div><div class=\"tresbf-postcontent tresbf-postcontent-0 clearfix\"><div class=\"tresbf-article\"><p>Conhe\u00e7a toda legisla\u00e7\u00e3o que regulamenta os par\u00e2metros de atua\u00e7\u00e3o do mercado financeiro. As normas, regras e instru\u00e7\u00f5es s\u00e3o abrangentes e re\u00fanem desde conduta da corretora em rela\u00e7\u00e3o \u00e0s bolsas de valores at\u00e9 determina\u00e7\u00f5es sobre opera\u00e7\u00f5es sujeitas a procedimentos especiais.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/instrucao_CVM_N387_Cadastro_Ops_Bolsas.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Instru\u00e7\u00e3o 387<\/strong><\/a><br \/>Legisla\u00e7\u00e3o da CVM, de 28 de abril de 2003, trata dos procedimentos para a realiza\u00e7\u00e3o de opera\u00e7\u00f5es em preg\u00e3o e em sistemas eletr\u00f4nicos de negocia\u00e7\u00e3o de bolsas de valores e de mercadorias e futuros. Ela determina que as corretoras elaborem suas regras e par\u00e2metros de atua\u00e7\u00e3o na rela\u00e7\u00e3o com seus clientes. Este documento deve ser entregue aos clientes no per\u00edodo do cadastramento e deve conter defini\u00e7\u00f5es sobre as normas relativas \u00e0 recep\u00e7\u00e3o de ordens, ao tipo de ordens aceitas, \u00e0s confirma\u00e7\u00f5es e cancelamento de neg\u00f3cios, entre outras. Todas as regras devem ser previamente aprovadas pelas bolsas. Pelo poder de auto-regula\u00e7\u00e3o, as bolsas devem estabelecer regras de conduta para as corretoras no relacionamento com seus clientes e demais participantes do mercado. \u00c9 vedado \u00e0s corretoras aceitar ou cumprir ordens de clientes que n\u00e3o estejam previamente cadastrados; utilizar contas correntes coletivas e permitir a corretagem por pessoas n\u00e3o autorizadas pela CVM.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/instrucao_CVM_N387_Cadastro_Ops_Bolsas.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/resolucao_%20290_CA_Cadastro.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Resolu\u00e7\u00e3o 290<\/strong><\/a><br \/>Resolu\u00e7\u00e3o do Conselho de Administra\u00e7\u00e3o da BOVESPA, de 22 de julho de 2003, regulamenta e disp\u00f5e sobre a uniformiza\u00e7\u00e3o dos cadastros dos clientes das sociedades corretoras, em atendimento \u00e0s exig\u00eancias da Instru\u00e7\u00e3o CVM 387. Segundo esta resolu\u00e7\u00e3o, as corretoras dever\u00e3o manter cadastros atualizados de seus clientes, dentro de um padr\u00e3o m\u00ednimo de informa\u00e7\u00f5es.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/resolucao_%20290_CA_Cadastro.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/Manual_Bovespa_Homebroker.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Alerta do Mercado de Op\u00e7\u00f5es<\/strong><\/a><br \/>Antes de investir em op\u00e7\u00f5es, consulte os riscos que envolvem esse tipo de investimento.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/Manual_Bovespa_Homebroker.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/Lei_6385_consolidada.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Lei 6.385<\/strong><\/a><br \/>Criada em 31 de dezembro de 1964, a Lei disp\u00f5e sobre a cria\u00e7\u00e3o da Comiss\u00e3o de Valores Mobili\u00e1rios (CVM), o principal \u00f3rg\u00e3o regulador do mercado de capitais. A CVM \u00e9 uma entidade aut\u00e1rquica em regime especial, vinculada ao Minist\u00e9rio da Fazenda, com personalidade jur\u00eddica e patrim\u00f4nio pr\u00f3prios, dotada de autoridade administrativa independente, aus\u00eancia de subordina\u00e7\u00e3o hier\u00e1rquica, mandato fixo e estabilidade de seus dirigentes, autonomia financeira e or\u00e7ament\u00e1ria.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/Lei_6385_consolidada.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/resolucao_1656_Bolsas_de_Valores.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Resolu\u00e7\u00e3o 1.656<\/strong><\/a><br \/>A legisla\u00e7\u00e3o disciplina a constitui\u00e7\u00e3o , organiza\u00e7\u00e3o e o funcionamento das Bolsas de Valores. A Resolu\u00e7\u00e3o em vigor desde em 26 de outubro de 1989, torna as Bolsas de Valores associa\u00e7\u00f5es civis, sem fins lucrativos, tendo como objetivo manter o local adequado \u00e0s opera\u00e7\u00f5es de compra e venda de t\u00edtulos e valores mobili\u00e1rios, em mercado livre e aberto, organizado e fiscalizado pela pr\u00f3pria Bolsa. Al\u00e9m de dotar, permanentemente, o local ou sistema de todos os meios necess\u00e1rios \u00e0 pronta e eficiente realiza\u00e7\u00e3o e visibilidade das opera\u00e7\u00f5es, entre outras responsabilidades.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/resolucao_1656_Bolsas_de_Valores.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/resolucao_1655_Sociedades_Corretoras.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Resolu\u00e7\u00e3o 1.655<\/strong><\/a><br \/>Aprovada em 26 de outubro de 1989, esta Resolu\u00e7\u00e3o disciplina a constitui\u00e7\u00e3o, a organiza\u00e7\u00e3o e o funcionamento das sociedades corretoras de valores mobili\u00e1rios. Cabe \u00e0 sociedade corretora operar em recinto ou em sistema mantido pela bolsa de valores; intermediar oferta p\u00fablica e distribui\u00e7\u00e3o de t\u00edtulos e valores mobili\u00e1rios no mercado; comprar e vender t\u00edtulos e valores mobili\u00e1rios por conta pr\u00f3pria e de terceiros; entre outras.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/resolucao_1655_Sociedades_Corretoras.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/instrucao_CVM_N51_Conta_Margem.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Instru\u00e7\u00e3o 51<\/strong><\/a><br \/>Aprovada em 9 de junho de 1986, a Instru\u00e7\u00e3o 51, elaborada pela CVM, regulamenta a concess\u00e3o, pelas Sociedades Corretoras, de financiamento para compra de a\u00e7\u00f5es e o empr\u00e9stimo de a\u00e7\u00f5es para venda, dentro de determinados crit\u00e9rios, os chamados empr\u00e9stimos em Conta Margem. Em ambos os casos, s\u00e3o definidos os padr\u00f5es do contrato de financiamento. Assim como em qualquer concess\u00e3o de empr\u00e9stimo tamb\u00e9m dever\u00e3o oferecer garantias. Para fins de registro do financiamento concedido a corretora abrir\u00e1 uma conta corrente especial em nome de cada financiado. Em rela\u00e7\u00e3o ao volume total das opera\u00e7\u00f5es concedidas pela sociedade corretora ou distribuidora n\u00e3o poder\u00e1 exceder a cinco vezes o valor do respectivo patrim\u00f4nio l\u00edquido.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/instrucao_CVM_N51_Conta_Margem.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/instrucao_CVM_N168_Ops_Proced_Espec.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Instru\u00e7\u00e3o 168<\/strong><\/a><br \/>A Instru\u00e7\u00e3o da CVM, em vigor desde 23 de dezembro 1991, disp\u00f5e sobre as opera\u00e7\u00f5es sujeitas a procedimentos especiais nas bolsas de valores. \u00c9 o caso de elevada quantidade de a\u00e7\u00f5es ou direitos superior \u00e0 m\u00e9dia di\u00e1ria negociada nos \u00faltimos preg\u00f5es, qualquer bloco substancial, mesmo que a negocia\u00e7\u00e3o n\u00e3o envolva transfer\u00eancia de controle ou de pre\u00e7o sensivelmente superior ou inferior \u00e0 m\u00e9dia dos \u00faltimos preg\u00f5es. \u00c9 muito importante a leitura desta Instru\u00e7\u00e3o, pois \u00e9 atrav\u00e9s dela que algumas opera\u00e7\u00f5es j\u00e1 confirmadas, podem ser canceladas pela Bolsa, no caso de ocorr\u00eancia de alguma irregularidade ou n\u00e3o obedi\u00eancia aos par\u00e2metros e procedimentos aqui descritos.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/instrucao_CVM_N168_Ops_Proced_Espec.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/instrucao_CVM_N249_Emprestimos_Acoes.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Instru\u00e7\u00e3o 249<\/strong><\/a><br \/>Regulamentada pela CVM em 11 de abril de 1996, a Instru\u00e7\u00e3o disp\u00f5e sobre o empr\u00e9stimo de a\u00e7\u00f5es pelas entidades prestadoras de servi\u00e7os de liquida\u00e7\u00e3o, registro e cust\u00f3dia de a\u00e7\u00f5es. Pela norma, o servi\u00e7o de empr\u00e9stimo pelas institui\u00e7\u00f5es dever\u00e1 ter aprova\u00e7\u00e3o pr\u00e9via da CVM. Tamb\u00e9m regulamenta que as sociedades corretoras e distribuidoras de valores s\u00e3o as institui\u00e7\u00f5es que far\u00e3o a intermedia\u00e7\u00e3o das opera\u00e7\u00f5es. Determina quais as informa\u00e7\u00f5es dever\u00e3o ser mencionadas no contrato de empr\u00e9stimo.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/instrucao_CVM_N249_Emprestimos_Acoes.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/instrucao_CVM_N380_ops_internet.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Instru\u00e7\u00e3o 380<\/strong><\/a><br \/>Aprovada em 23 de dezembro de 2002, a Instru\u00e7\u00e3o da CVM regulamenta normas e procedimentos a serem observados pelas Sociedades Corretoras e demais participantes nas opera\u00e7\u00f5es realizadas via internet em bolsas de valores e mercados de balc\u00e3o organizado. Entre os procedimentos, as corretoras eletr\u00f4nicas dever\u00e3o constar em seus sites linguagem acess\u00edvel e clara aos investidores. Al\u00e9m de ter instru\u00e7\u00f5es detalhadas sobre o uso do sistema de negocia\u00e7\u00e3o via internet. A instru\u00e7\u00e3o trata ainda da capacidade de atendimento aos seus clientes, abordando o tempo decorrido entre o recebimento de uma ordem enviada pelo cliente \u00e0 corretora eletr\u00f4nica e a resposta da corretora para seu cliente. A quest\u00e3o da seguran\u00e7a tamb\u00e9m \u00e9 abordada, determinando garante opera\u00e7\u00f5es seguras e o sigilo de toda a informa\u00e7\u00e3o sobre seus clientes, suas ordens de compra ou venda de ativos e sua carteira de investimentos, bem como sua comunica\u00e7\u00e3o com os clientes, com a utiliza\u00e7\u00e3o de elevados padr\u00f5es tecnol\u00f3gicos de seguran\u00e7a de rede.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/instrucao_CVM_N380_ops_internet.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/instrucao_CVM_N400_Ofertas_Publicas.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Instru\u00e7\u00e3o N\u00ba 400<\/strong><\/a><br \/>Em vigor desde 29 de dezembro de 2003, elaborada pela CVM, a legisla\u00e7\u00e3o regulamenta ofertas p\u00fablicas de distribui\u00e7\u00e3o, nos mercados prim\u00e1rio e secund\u00e1rio, de a\u00e7\u00f5es em bolsa de valores, bolsa de mercadorias e de futuros e entidade do mercado de balc\u00e3o organizado. Segundo a Instru\u00e7\u00e3o, toda oferta p\u00fablica para distribui\u00e7\u00e3o de a\u00e7\u00f5es no mercado dever\u00e1 obter registro junto a CVM. O pedido de registro ser\u00e1 analisado no per\u00edodo de 20 dias. Ela disp\u00f5e sobre todos os procedimentos que envolvem a oferta p\u00fablica de a\u00e7\u00f5es no mercado desde o registro at\u00e9 informa\u00e7\u00f5es que dever\u00e3o constar no material de divulga\u00e7\u00e3o ao p\u00fablico.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/instrucao_CVM_N400_Ofertas_Publicas.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/Lei_N_9613_%20Lavagem_Dinheiro.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Lei N\u00ba 9.613<\/strong><\/a><br \/>Aprovada em 3 de mar\u00e7o de 1998, a Lei 9.613 trata dos crimes de \"lavagem\" de dinheiro, da utiliza\u00e7\u00e3o do sistema financeiro para a\u00e7\u00f5es il\u00edcitas e cria o Conselho de Controle de Atividades Financeiras (COAF). O COAF tem como objetivo disciplinar, aplicar penas administrativas, receber, examinar e identificar as ocorr\u00eancias suspeitas de atividades il\u00edcitas previstas nesta Lei, sem preju\u00edzo da compet\u00eancia de outros \u00f3rg\u00e3os e entidades. A Lei caracteriza como crime pass\u00edvel de pena de reclus\u00e3o, ocultar ou dissimular a natureza, origem e localiza\u00e7\u00e3o, movimenta\u00e7\u00e3o ou propriedade de bens, direitos ou valores provenientes de crimes de tr\u00e1fico il\u00edcito de subst\u00e2ncias entorpecentes ou drogas afins; terrorismo; contrabando ou tr\u00e1fico de armas, muni\u00e7\u00f5es ou material destinado \u00e0 sua produ\u00e7\u00e3o; extors\u00e3o mediante seq\u00fcestro; a\u00e7\u00f5es contra a Administra\u00e7\u00e3o P\u00fablica; contra o sistema financeiro nacional e os praticados por organiza\u00e7\u00e3o criminosa. A penalidade prevista varia de tr\u00eas a dez anos de reclus\u00e3o, mais multa. A Lei determina que as entidades respons\u00e1veis pela intermedia\u00e7\u00e3o, negocia\u00e7\u00e3o devam manter cadastro atualizado de seus clientes, al\u00e9m do registro de todas as opera\u00e7\u00f5es realizadas por seus clientes, que devem estar \u00e0 disposi\u00e7\u00e3o para atender qualquer pedido de autoridade competente.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/Lei_N_9613_%20Lavagem_Dinheiro.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/instrucao_CVM_%20N301_Lav_Dinh.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Instru\u00e7\u00e3o 301<\/strong><\/a><br \/>A legisla\u00e7\u00e3o prop\u00f5e detalhamento de quatro artigos da Lei 9.613 que disp\u00f5e sobre crimes de \u201clavagem\u201d de dinheiro e preven\u00e7\u00e3o da utiliza\u00e7\u00e3o do sistema financeiro para opera\u00e7\u00f5es il\u00edcitas. Em vigor desde 16 de abril de 1999, a Instru\u00e7\u00e3o Normativa da CVM estabelece crit\u00e9rios detalhados do artigo 10 (Incisos I e II), artigo 11 (Incisos I e II) e artigos 12 e 13 da Lei Federal 9.613. A Instru\u00e7\u00e3o define, por exemplo, as informa\u00e7\u00f5es que devem ser indispens\u00e1veis para os cadastros de pessoa f\u00edsica e jur\u00eddica. Tamb\u00e9m estabelece o valor para registro de toda transa\u00e7\u00e3o financeira, envolvendo t\u00edtulos ou valores mobili\u00e1rios, seja igual ou superior a R$ 10 mil. Segundo a Instru\u00e7\u00e3o, as corretoras dever\u00e3o conservar os cadastros pelo per\u00edodo m\u00ednimo de cinco anos, ficando \u00e0 disposi\u00e7\u00e3o da CVM, entre outros itens. Ela lista as situa\u00e7\u00f5es pr\u00e1ticas que configuram os crimes definidos na Lei 9613 e que devem ser comunicados \u00e0 CVM pelas corretoras e bolsas quando tiverem ind\u00edcios ou configurarem crimes caracterizados pelo documento.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/instrucao_CVM_%20N301_Lav_Dinh.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/Resolucao%202817_conta_eletronica.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Resolu\u00e7\u00e3o 2817<\/strong><\/a><br \/>Aprovada em 22 de fevereiro de 2001 pelo Banco Central do Brasil, a legisla\u00e7\u00e3o permite \u00e0s institui\u00e7\u00f5es banc\u00e1rias ou financeiras a abertura de conta e movimenta\u00e7\u00e3o de contas exclusivamente pelo meio eletr\u00f4nico.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/Resolucao%202817_conta_eletronica.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/BVSP_manual_regula_completo.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Regulamento de Opera\u00e7\u00f5es Bolsa de Valores de S\u00e3o Paulo<\/strong><\/a><br \/>Re\u00fane a consolida\u00e7\u00e3o das regras do sistema de negocia\u00e7\u00e3o na Bovespa, com cap\u00edtulos dedicados aos tipos de negocia\u00e7\u00e3o, ao preg\u00e3o eletr\u00f4nico, local de negocia\u00e7\u00e3o, aos operadores e auxiliares do preg\u00e3o, after market, mercado \u00e0 vista, a termo, futuro e de op\u00e7\u00f5es, formadores de mercado, ordens de compra e venda, as apregoa\u00e7\u00f5es, corre\u00e7\u00e3o e cancelamento de neg\u00f3cios, direitos e obriga\u00e7\u00f5es das sociedades corretoras, entre outros.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/BVSP_manual_regula_completo.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/Regras_de_Liquidacao_CBLC.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Regras de Liquida\u00e7\u00e3o da CBLC<\/strong><\/a><br \/>S\u00e3o todas as etapas que envolvem a liquida\u00e7\u00e3o e cust\u00f3dia de a\u00e7\u00f5es e os procedimentos operacionais da Companhia Brasileira de Liquida\u00e7\u00e3o e Cust\u00f3dia. O documento dividido em oito cap\u00edtulos aborda temas como cadastro de participantes e investidores, registro e aceita\u00e7\u00e3o de opera\u00e7\u00f5es, compensa\u00e7\u00e3o e liquida\u00e7\u00e3o, etapas do ciclo de liquida\u00e7\u00e3o, entrega de ativos, tratamento de falta de entrega, falta de pagamento, gerenciamento de riscos, crit\u00e9rios de aceita\u00e7\u00e3o de opera\u00e7\u00f5es, servi\u00e7o de cust\u00f3dia, entre outros assuntos relevantes.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/Regras_de_Liquidacao_CBLC.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/Regulamento_Operacoes_CBLC.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Regulamento de Opera\u00e7\u00f5es da CBLC<\/strong><\/a><br \/>O regulamento tem como objetivo disciplinar as atividades da Companhia Brasileira de Liquida\u00e7\u00e3o e Cust\u00f3dia (CBLC). Al\u00e9m disso, regulamenta os princ\u00edpios e regras gerais para institui\u00e7\u00f5es ou pessoas com as quais mant\u00e9m qualquer tipo de rela\u00e7\u00e3o jur\u00eddica contratual ou operacional.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/Regulamento_Operacoes_CBLC.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/Codigo_Etica_da_BMF.pdf\" target=\"_blank\" rel=\"noopener\"><strong>C\u00f3digo de \u00c9tica dos participantes da Bolsa de Mercadorias e de Futuros (BM&F)<\/strong><\/a><br \/>Estabelece os princ\u00edpios gerais e as regras que regem a conduta dos participantes nos mercados administrados pela BM&F; utiliza\u00e7\u00e3o dos Sistemas de Negocia\u00e7\u00e3o e\/ou dos Sistemas de Registro desenvolvidos ou administrados pela BM&F; utiliza\u00e7\u00e3o de qualquer servi\u00e7o prestado pela BM&F nos termos de seus Estatutos Sociais. O C\u00f3digo prev\u00ea que os atos e as negocia\u00e7\u00f5es realizados na BM&F dever\u00e3o estar de acordo com as regras e as finalidades das modalidades operacionais adotadas, em sintonia com os mecanismos de negocia\u00e7\u00e3o e o processo de forma\u00e7\u00e3o de pre\u00e7os. \u00c9 vedada a atua\u00e7\u00e3o dos participantes, isolada ou em conjunto, com objetivo de afetar os mecanismos de forma\u00e7\u00e3o de pre\u00e7os, criando condi\u00e7\u00f5es artificiais de oferta ou demanda, ou seja, de manipula\u00e7\u00e3o do mercado.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/Codigo_Etica_da_BMF.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/Regulamento_Webtr.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Regulamento Webtrading<\/strong><\/a><br \/>Este regulamento disciplina as opera\u00e7\u00f5es realizadas via Webtrading, o sistema eletr\u00f4nico da BM&F, para a compra e venda de ativos financeiros pela internet. Ele especifica as condi\u00e7\u00f5es t\u00e9cnicas para acesso ao sistema, os par\u00e2metros para cadastramento dos clientes, os tipos de contratos a serem negociados, a administra\u00e7\u00e3o dos riscos e as garantias a serem exigidas para a realiza\u00e7\u00e3o dos neg\u00f3cios.<\/p><p>Cartilha do investidor>>\u00a0<a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/Regulamento_Webtr.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/regulamento_tesourodireto.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Regulamento do Tesouro Direto<\/strong><\/a><br \/>Este documento re\u00fane as regras que disciplinam as atividades da Secretaria do Tesouro Nacional (STN), Companhia Brasileira de Liquida\u00e7\u00e3o e Cust\u00f3dia (CBLC), dos agentes de cust\u00f3dia da CBLC e dos Investidores nas opera\u00e7\u00f5es envolvendo t\u00edtulos p\u00fablicos federais no sistema denominado \u201cTesouro Direto\u201d. Os Agentes de Cust\u00f3dia, no caso as corretoras, s\u00e3o respons\u00e1veis pela autenticidade das informa\u00e7\u00f5es cadastrais do Investidor, devendo manter em seus arquivos documenta\u00e7\u00e3o e ficha cadastrais sempre atualizadas, sob pena da aplica\u00e7\u00e3o das penalidades previstas neste Regulamento e nas demais normas da CBLC. Eles devem enviar sempre que for solicitada, documenta\u00e7\u00e3o comprobat\u00f3ria das informa\u00e7\u00f5es cadastrais dos Investidores. O acesso do investidor ser\u00e1 realizado pela internet, diretamente pelo site oficial do Tesouro Direto, mediante preenchimento de seu CPF e senha. A habilita\u00e7\u00e3o do investidor dever\u00e1 ser por interm\u00e9dio de um agente de cust\u00f3dia para acessar o Tesouro Direto e receber\u00e1 da CBLC, em seu endere\u00e7o eletr\u00f4nico, uma senha provis\u00f3ria para acesso ao Tesouro Direto. Esta senha possui um prazo de validade predefinido e dever\u00e1 ser alterada, pelo Investidor, em seu primeiro acesso ao Tesouro Direto.<\/p><p><a href=\"https:\/\/www.wintrade.com.br\/site\/Universidade\/leis\/regulamento_tesourodireto.pdf\" target=\"_blank\" rel=\"noopener\">Confira a \u00edntegra>><\/a><\/p><\/div><\/div>","_et_gb_content_width":"","footnotes":""},"class_list":["post-301","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.amarilfranklin.com.br\/index.php\/wp-json\/wp\/v2\/pages\/301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amarilfranklin.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.amarilfranklin.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.amarilfranklin.com.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amarilfranklin.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=301"}],"version-history":[{"count":0,"href":"https:\/\/www.amarilfranklin.com.br\/index.php\/wp-json\/wp\/v2\/pages\/301\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.amarilfranklin.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}